{"id":95893,"date":"2022-12-07T21:48:36","date_gmt":"2022-12-07T20:48:36","guid":{"rendered":"https:\/\/atlantics.de\/rutsche\/kindergarten-mikado\/"},"modified":"2026-03-15T15:50:36","modified_gmt":"2026-03-15T14:50:36","slug":"kindergarten-mikado","status":"publish","type":"rutsche","link":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/","title":{"rendered":"Kindergarten Mikado"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":95900,"menu_order":0,"template":"","meta":{"_acf_changed":false},"rutschen-typ":[237],"rutschen-kategorie":[236,329,235],"class_list":["post-95893","rutsche","type-rutsche","status-publish","hentry","rutschen-typ-tunnelrutsjebaner","rutschen-kategorie-evakueringssklier","rutschen-kategorie-roersklier","rutschen-kategorie-toerre-sklier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kindergarten Mikado - atlantics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kindergarten Mikado - atlantics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/\" \/>\n<meta property=\"og:site_name\" content=\"atlantics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-15T14:50:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/barnehage-mikado\\\/kindergarten-mikado\\\/\",\"url\":\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/barnehage-mikado\\\/kindergarten-mikado\\\/\",\"name\":\"Kindergarten Mikado - atlantics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/no\\\/#website\"},\"datePublished\":\"2022-12-07T20:48:36+00:00\",\"dateModified\":\"2026-03-15T14:50:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/barnehage-mikado\\\/kindergarten-mikado\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/barnehage-mikado\\\/kindergarten-mikado\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/barnehage-mikado\\\/kindergarten-mikado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/atlantics.de\\\/no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sklier\",\"item\":\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barnehage Mikado\",\"item\":\"https:\\\/\\\/atlantics.de\\\/no\\\/rutsche\\\/barnehage-mikado\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Kindergarten Mikado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/atlantics.de\\\/no\\\/\",\"name\":\"atlantics\",\"description\":\"Manufaktur f\u00fcr Edelstahlrutschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/atlantics.de\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kindergarten Mikado - atlantics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/","og_locale":"nb_NO","og_type":"article","og_title":"Kindergarten Mikado - atlantics","og_url":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/","og_site_name":"atlantics","article_modified_time":"2026-03-15T14:50:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/","url":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/","name":"Kindergarten Mikado - atlantics","isPartOf":{"@id":"https:\/\/atlantics.de\/no\/#website"},"datePublished":"2022-12-07T20:48:36+00:00","dateModified":"2026-03-15T14:50:36+00:00","breadcrumb":{"@id":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/kindergarten-mikado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/atlantics.de\/no\/"},{"@type":"ListItem","position":2,"name":"Sklier","item":"https:\/\/atlantics.de\/no\/rutsche\/"},{"@type":"ListItem","position":3,"name":"Barnehage Mikado","item":"https:\/\/atlantics.de\/no\/rutsche\/barnehage-mikado\/"},{"@type":"ListItem","position":4,"name":"Kindergarten Mikado"}]},{"@type":"WebSite","@id":"https:\/\/atlantics.de\/no\/#website","url":"https:\/\/atlantics.de\/no\/","name":"atlantics","description":"Manufaktur f\u00fcr Edelstahlrutschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atlantics.de\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"}]}},"_links":{"self":[{"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/rutsche\/95893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/rutsche"}],"about":[{"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/types\/rutsche"}],"version-history":[{"count":0,"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/rutsche\/95893\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/rutsche\/95900"}],"wp:attachment":[{"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/media?parent=95893"}],"wp:term":[{"taxonomy":"rutschen-typ","embeddable":true,"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/rutschen-typ?post=95893"},{"taxonomy":"rutschen-kategorie","embeddable":true,"href":"https:\/\/atlantics.de\/no\/wp-json\/wp\/v2\/rutschen-kategorie?post=95893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}