{"id":85858,"date":"2017-08-05T14:50:23","date_gmt":"2017-08-05T12:50:23","guid":{"rendered":"https:\/\/atlantics.de\/rutsche\/parco-degli-scivoli-nel-bosco-di-golm-2\/"},"modified":"2026-03-14T21:54:53","modified_gmt":"2026-03-14T20:54:53","slug":"parco-degli-scivoli-nel-bosco-di-golm-2","status":"publish","type":"rutsche","link":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/","title":{"rendered":"Parco degli scivoli nel bosco di Golm"},"content":{"rendered":"","protected":false},"featured_media":85859,"parent":85947,"menu_order":0,"template":"","meta":{"_acf_changed":false},"rutschen-typ":[241],"rutschen-kategorie":[239,330],"class_list":["post-85858","rutsche","type-rutsche","status-publish","has-post-thumbnail","hentry","rutschen-typ-scivoli-a-tunnel","rutschen-kategorie-scivoli-a-secco","rutschen-kategorie-scivoli-su-pendio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parco degli scivoli nel bosco di Golm - atlantics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parco degli scivoli nel bosco di Golm - atlantics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/\" \/>\n<meta property=\"og:site_name\" content=\"atlantics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T20:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atlantics.de\/wp-content\/uploads\/2018\/11\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2554\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/\",\"url\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/\",\"name\":\"Parco degli scivoli nel bosco di Golm - atlantics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atlantics.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg\",\"datePublished\":\"2017-08-05T12:50:23+00:00\",\"dateModified\":\"2026-03-14T20:54:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/atlantics.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg\",\"contentUrl\":\"https:\\\/\\\/atlantics.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg\",\"width\":2554,\"height\":1700,\"caption\":\"Scivoli in acciaio inox atlantics nel parco scivoli nel bosco Golm in Austria, scivoli a tunnel, scivoli di pendenza, aree sciistiche ed escursionistiche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/parco-degli-scivoli-nel-bosco-di-golm-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/atlantics.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scivoli\",\"item\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Parco scivoli nel bosco Golm\",\"item\":\"https:\\\/\\\/atlantics.de\\\/it\\\/rutsche\\\/parco-scivoli-nel-bosco-golm\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Parco degli scivoli nel bosco di Golm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/atlantics.de\\\/it\\\/\",\"name\":\"atlantics\",\"description\":\"Manufaktur f\u00fcr Edelstahlrutschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/atlantics.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parco degli scivoli nel bosco di Golm - atlantics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/","og_locale":"it_IT","og_type":"article","og_title":"Parco degli scivoli nel bosco di Golm - atlantics","og_url":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/","og_site_name":"atlantics","article_modified_time":"2026-03-14T20:54:53+00:00","og_image":[{"width":2554,"height":1700,"url":"https:\/\/atlantics.de\/wp-content\/uploads\/2018\/11\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/","url":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/","name":"Parco degli scivoli nel bosco di Golm - atlantics","isPartOf":{"@id":"https:\/\/atlantics.de\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/#primaryimage"},"image":{"@id":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/#primaryimage"},"thumbnailUrl":"https:\/\/atlantics.de\/wp-content\/uploads\/2018\/11\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg","datePublished":"2017-08-05T12:50:23+00:00","dateModified":"2026-03-14T20:54:53+00:00","breadcrumb":{"@id":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/#primaryimage","url":"https:\/\/atlantics.de\/wp-content\/uploads\/2018\/11\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg","contentUrl":"https:\/\/atlantics.de\/wp-content\/uploads\/2018\/11\/atlantics_edelstahlrutschen_waldrutschenpark-golm_tschagguns-oesterreich_roehren_178249_DSC3535.jpg","width":2554,"height":1700,"caption":"Scivoli in acciaio inox atlantics nel parco scivoli nel bosco Golm in Austria, scivoli a tunnel, scivoli di pendenza, aree sciistiche ed escursionistiche"},{"@type":"BreadcrumbList","@id":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/parco-degli-scivoli-nel-bosco-di-golm-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/atlantics.de\/it\/"},{"@type":"ListItem","position":2,"name":"Scivoli","item":"https:\/\/atlantics.de\/it\/rutsche\/"},{"@type":"ListItem","position":3,"name":"Parco scivoli nel bosco Golm","item":"https:\/\/atlantics.de\/it\/rutsche\/parco-scivoli-nel-bosco-golm\/"},{"@type":"ListItem","position":4,"name":"Parco degli scivoli nel bosco di Golm"}]},{"@type":"WebSite","@id":"https:\/\/atlantics.de\/it\/#website","url":"https:\/\/atlantics.de\/it\/","name":"atlantics","description":"Manufaktur f\u00fcr Edelstahlrutschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atlantics.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/rutsche\/85858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/rutsche"}],"about":[{"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/types\/rutsche"}],"version-history":[{"count":0,"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/rutsche\/85858\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/rutsche\/85947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/media\/85859"}],"wp:attachment":[{"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/media?parent=85858"}],"wp:term":[{"taxonomy":"rutschen-typ","embeddable":true,"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/rutschen-typ?post=85858"},{"taxonomy":"rutschen-kategorie","embeddable":true,"href":"https:\/\/atlantics.de\/it\/wp-json\/wp\/v2\/rutschen-kategorie?post=85858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}