{"id":94710,"date":"2022-11-04T07:46:19","date_gmt":"2022-11-04T06:46:19","guid":{"rendered":"https:\/\/atlantics.de\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/"},"modified":"2022-11-04T07:46:19","modified_gmt":"2022-11-04T06:46:19","slug":"lilidorei-en-the-alnwick-garden-2","status":"publish","type":"rutsche","link":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/","title":{"rendered":"Lilidorei en The Alnwick Garden"},"content":{"rendered":"","protected":false},"featured_media":91980,"parent":91979,"menu_order":0,"template":"","meta":{"_acf_changed":false},"rutschen-typ":[234],"rutschen-kategorie":[298,335,232,337],"class_list":["post-94710","rutsche","type-rutsche","status-publish","has-post-thumbnail","hentry","rutschen-typ-toboganes-tunel","rutschen-kategorie-parques-de-ocio","rutschen-kategorie-toboganes-de-aventura","rutschen-kategorie-toboganes-secos","rutschen-kategorie-toboganes-tubulares"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lilidorei en The Alnwick Garden - atlantics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lilidorei en The Alnwick Garden - atlantics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/\" \/>\n<meta property=\"og:site_name\" content=\"atlantics\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atlantics.de\/wp-content\/uploads\/2023\/11\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/\",\"url\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/\",\"name\":\"Lilidorei en The Alnwick Garden - atlantics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atlantics.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg\",\"datePublished\":\"2022-11-04T06:46:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/atlantics.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/atlantics.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg\",\"width\":2560,\"height\":1657,\"caption\":\"Toboganes de acero inoxidable de atlantics en el parque tem\u00e1tico Lilidorei at the Alnwick Garden, el castillo de Harry Potter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/lilidorei-en-the-alnwick-garden-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/atlantics.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toboganes\",\"item\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lilidorei at The Alnwick Garden\",\"item\":\"https:\\\/\\\/atlantics.de\\\/es\\\/rutsche\\\/lilidorei-at-the-alnwick-garden\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lilidorei en The Alnwick Garden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/atlantics.de\\\/es\\\/\",\"name\":\"atlantics\",\"description\":\"Manufaktur f\u00fcr Edelstahlrutschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/atlantics.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lilidorei en The Alnwick Garden - atlantics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/","og_locale":"es_ES","og_type":"article","og_title":"Lilidorei en The Alnwick Garden - atlantics","og_url":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/","og_site_name":"atlantics","og_image":[{"width":2560,"height":1657,"url":"https:\/\/atlantics.de\/wp-content\/uploads\/2023\/11\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/","url":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/","name":"Lilidorei en The Alnwick Garden - atlantics","isPartOf":{"@id":"https:\/\/atlantics.de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/#primaryimage"},"image":{"@id":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/#primaryimage"},"thumbnailUrl":"https:\/\/atlantics.de\/wp-content\/uploads\/2023\/11\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg","datePublished":"2022-11-04T06:46:19+00:00","breadcrumb":{"@id":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/#primaryimage","url":"https:\/\/atlantics.de\/wp-content\/uploads\/2023\/11\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg","contentUrl":"https:\/\/atlantics.de\/wp-content\/uploads\/2023\/11\/atlantics_edelstahlrutschen_lilidorei-at-the-alnwick-garden_tunnel_fun_218818_251A9877-scaled.jpg","width":2560,"height":1657,"caption":"Toboganes de acero inoxidable de atlantics en el parque tem\u00e1tico Lilidorei at the Alnwick Garden, el castillo de Harry Potter"},{"@type":"BreadcrumbList","@id":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/lilidorei-en-the-alnwick-garden-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/atlantics.de\/es\/"},{"@type":"ListItem","position":2,"name":"Toboganes","item":"https:\/\/atlantics.de\/es\/rutsche\/"},{"@type":"ListItem","position":3,"name":"Lilidorei at The Alnwick Garden","item":"https:\/\/atlantics.de\/es\/rutsche\/lilidorei-at-the-alnwick-garden\/"},{"@type":"ListItem","position":4,"name":"Lilidorei en The Alnwick Garden"}]},{"@type":"WebSite","@id":"https:\/\/atlantics.de\/es\/#website","url":"https:\/\/atlantics.de\/es\/","name":"atlantics","description":"Manufaktur f\u00fcr Edelstahlrutschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atlantics.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/rutsche\/94710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/rutsche"}],"about":[{"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/types\/rutsche"}],"version-history":[{"count":0,"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/rutsche\/94710\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/rutsche\/91979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/media\/91980"}],"wp:attachment":[{"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/media?parent=94710"}],"wp:term":[{"taxonomy":"rutschen-typ","embeddable":true,"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/rutschen-typ?post=94710"},{"taxonomy":"rutschen-kategorie","embeddable":true,"href":"https:\/\/atlantics.de\/es\/wp-json\/wp\/v2\/rutschen-kategorie?post=94710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}