{"id":45094,"date":"2017-07-16T07:11:35","date_gmt":"2017-07-16T05:11:35","guid":{"rendered":"https:\/\/atlantics.de\/rutsche\/spielplatz-bergen\/"},"modified":"2026-02-20T17:33:53","modified_gmt":"2026-02-20T16:33:53","slug":"spielplatz-bergen","status":"publish","type":"rutsche","link":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/","title":{"rendered":"Playground Bergen"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"rutschen-typ":[86],"rutschen-kategorie":[84,87],"class_list":["post-45094","rutsche","type-rutsche","status-publish","hentry","rutschen-typ-tunnel-slides","rutschen-kategorie-dry-slides","rutschen-kategorie-playground-slides"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playground Bergen - atlantics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playground Bergen - atlantics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/\" \/>\n<meta property=\"og:site_name\" content=\"atlantics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T16:33:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/en\\\/rutsche\\\/spielplatz-bergen\\\/\",\"url\":\"https:\\\/\\\/atlantics.de\\\/en\\\/rutsche\\\/spielplatz-bergen\\\/\",\"name\":\"Playground Bergen - atlantics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/en\\\/#website\"},\"datePublished\":\"2017-07-16T05:11:35+00:00\",\"dateModified\":\"2026-02-20T16:33:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atlantics.de\\\/en\\\/rutsche\\\/spielplatz-bergen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atlantics.de\\\/en\\\/rutsche\\\/spielplatz-bergen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/en\\\/rutsche\\\/spielplatz-bergen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/atlantics.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rutschen\",\"item\":\"https:\\\/\\\/atlantics.de\\\/en\\\/rutsche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Playground Bergen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/atlantics.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/atlantics.de\\\/en\\\/\",\"name\":\"atlantics\",\"description\":\"Manufaktur f\u00fcr Edelstahlrutschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/atlantics.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playground Bergen - atlantics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/","og_locale":"en_US","og_type":"article","og_title":"Playground Bergen - atlantics","og_url":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/","og_site_name":"atlantics","article_modified_time":"2026-02-20T16:33:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/","url":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/","name":"Playground Bergen - atlantics","isPartOf":{"@id":"https:\/\/atlantics.de\/en\/#website"},"datePublished":"2017-07-16T05:11:35+00:00","dateModified":"2026-02-20T16:33:53+00:00","breadcrumb":{"@id":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/atlantics.de\/en\/rutsche\/spielplatz-bergen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/atlantics.de\/en\/"},{"@type":"ListItem","position":2,"name":"Rutschen","item":"https:\/\/atlantics.de\/en\/rutsche\/"},{"@type":"ListItem","position":3,"name":"Playground Bergen"}]},{"@type":"WebSite","@id":"https:\/\/atlantics.de\/en\/#website","url":"https:\/\/atlantics.de\/en\/","name":"atlantics","description":"Manufaktur f\u00fcr Edelstahlrutschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atlantics.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/rutsche\/45094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/rutsche"}],"about":[{"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/types\/rutsche"}],"version-history":[{"count":0,"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/rutsche\/45094\/revisions"}],"wp:attachment":[{"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/media?parent=45094"}],"wp:term":[{"taxonomy":"rutschen-typ","embeddable":true,"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/rutschen-typ?post=45094"},{"taxonomy":"rutschen-kategorie","embeddable":true,"href":"https:\/\/atlantics.de\/en\/wp-json\/wp\/v2\/rutschen-kategorie?post=45094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}